{"id":6071,"date":"2025-09-09T12:44:53","date_gmt":"2025-09-09T10:44:53","guid":{"rendered":"https:\/\/www.scuolamonterisi.edu.it\/?p=6071"},"modified":"2025-09-09T12:44:53","modified_gmt":"2025-09-09T10:44:53","slug":"avviso-n-3-autorizzazione-uscita-autonoma-alunni-scuola-secondaria-di-primo-grado","status":"publish","type":"post","link":"https:\/\/www.scuolamonterisi.edu.it\/index.php\/2025\/09\/09\/avviso-n-3-autorizzazione-uscita-autonoma-alunni-scuola-secondaria-di-primo-grado\/","title":{"rendered":"AVVISO N.3 Autorizzazione uscita autonoma alunni scuola secondaria di primo grado"},"content":{"rendered":"\n<p>Con la presente si comunica che sono disponibili, in allegato alla presente e nell\u2019apposita Area MODULISTICA-GENITORI del sito, i moduli relativi all\u2019autorizzazione all\u2019uscita autonoma (esclusivamente Scuola Secondaria di Primo Grado).<\/p>\n\n\n\n<p>I moduli, corredati di fotocopia dei documenti identificativi e debitamente compilati e firmati, potranno essere consegnati dagli alunni, entro <strong>MERCOLEDI 17<\/strong> <strong>SETTEMBRE<\/strong> al docente presente in aula; in caso non venisse consegnata tale documentazione, l\u2019alunno non potr\u00e0 uscire autonomamente, n\u00e9 potr\u00e0 essere consegnato a terzi e dovr\u00e0 essere prelevato dai genitori all\u2019uscita di scuola. I docenti consegneranno suddette documentazioni agli uffici di segreteria area alunni.<\/p>\n\n\n\n<p>Le autorizzazioni corredate dai documenti di identit\u00e0 dei genitori\/tutori potranno essere consegnate anche direttamente agli uffici di segreteria della sede centrale di via Loria negli orari di segreteria (dal LUNERDI al VENERDI dalle ore 10:30 alle ore 12:30) o trasmetterla via mail ( <a href=\"mailto:saic8cf006@istruzione.it\">saic8cf006@istruzione.it<\/a> )<\/p>\n\n\n\n<p>Si ricorda inoltre che le autorizzazioni all\u2019uscita autonoma presentate nel precedente anno scolastico non sono pi\u00f9 valide, pertanto, vanno ripresentate per l\u2019anno scolastico 2025\/2026. Si ringrazia per la consueta e fattiva collaborazione.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong><a href=\"https:\/\/www.scuolamonterisi.edu.it\/index.php\/download\/uscita-autonoma\/\">MODULO USCITA AUTONOMA<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con la presente si comunica che sono disponibili, in allegato alla presente e nell\u2019apposita Area MODULISTICA-GENITORI del sito, i moduli relativi all\u2019autorizzazione all\u2019uscita autonoma (esclusivamente Scuola Secondaria di Primo Grado). I moduli, corredati di fotocopia dei documenti identificativi e debitamente compilati e firmati, potranno essere consegnati dagli alunni, entro MERCOLEDI <a class=\"read-more\" href=\"https:\/\/www.scuolamonterisi.edu.it\/index.php\/2025\/09\/09\/avviso-n-3-autorizzazione-uscita-autonoma-alunni-scuola-secondaria-di-primo-grado\/\">Read More&#8230;<\/a><\/p>\n","protected":false},"author":1,"featured_media":1784,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[65,72,71],"tags":[],"_links":{"self":[{"href":"https:\/\/www.scuolamonterisi.edu.it\/index.php\/wp-json\/wp\/v2\/posts\/6071"}],"collection":[{"href":"https:\/\/www.scuolamonterisi.edu.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.scuolamonterisi.edu.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.scuolamonterisi.edu.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.scuolamonterisi.edu.it\/index.php\/wp-json\/wp\/v2\/comments?post=6071"}],"version-history":[{"count":1,"href":"https:\/\/www.scuolamonterisi.edu.it\/index.php\/wp-json\/wp\/v2\/posts\/6071\/revisions"}],"predecessor-version":[{"id":6072,"href":"https:\/\/www.scuolamonterisi.edu.it\/index.php\/wp-json\/wp\/v2\/posts\/6071\/revisions\/6072"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.scuolamonterisi.edu.it\/index.php\/wp-json\/wp\/v2\/media\/1784"}],"wp:attachment":[{"href":"https:\/\/www.scuolamonterisi.edu.it\/index.php\/wp-json\/wp\/v2\/media?parent=6071"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.scuolamonterisi.edu.it\/index.php\/wp-json\/wp\/v2\/categories?post=6071"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.scuolamonterisi.edu.it\/index.php\/wp-json\/wp\/v2\/tags?post=6071"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}